{"id":6640,"date":"2023-05-02T16:14:11","date_gmt":"2023-05-02T10:44:11","guid":{"rendered":"https:\/\/gadgetsguruji.in\/?post_type=product&#038;p=6640"},"modified":"2023-12-28T10:43:59","modified_gmt":"2023-12-28T05:13:59","slug":"shree-ganesh-design-02-apple-iphone-11-mobile-cover","status":"publish","type":"product","link":"https:\/\/gadgetsguruji.in\/index.php\/product\/shree-ganesh-design-02-apple-iphone-11-mobile-cover\/","title":{"rendered":"Shree Ganesh Design 02 Mobile Cover"},"content":{"rendered":"<div class=\"icon-box featured-box icon-box-left text-left\">\n<div class=\"icon-box-img\">\n<div class=\"icon\">\n<ul>\n<li class=\"icon-inner\"><span style=\"font-size: 16px;\">Thin &amp; light Poly-carbonate case<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"icon-box featured-box icon-box-left text-left\">\n<div class=\"icon-box-img\">\n<div class=\"icon\">\n<ul>\n<li class=\"icon-inner\"><span style=\"font-size: 16px;\">Smooth &amp; seam-free surface<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"icon-box featured-box icon-box-left text-left\">\n<div class=\"icon-box-img\">\n<div class=\"icon\">\n<ul>\n<li class=\"icon-inner\"><span style=\"font-size: 16px;\">Photo-realistic print quality<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"icon-box featured-box icon-box-left text-left\">\n<div class=\"icon-box-text last-reset\">\n<ul>\n<li>Edge to edge Full matte finish Printing<\/li>\n<\/ul>\n<ul>\n<li>Delivery in 5-7 working days<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div class=\"icon-box featured-box icon-box-left text-left\">\n<div class=\"icon-box-text last-reset\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Thin &amp; light Poly-carbonate case Smooth &amp; seam-free surface Photo-realistic print quality Edge to edge Full matte finish Printing Delivery in 5-7 working days<\/p>\n","protected":false},"featured_media":81795,"comment_status":"open","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","_joinchat":[]},"product_cat":[61,73,96],"product_tag":[],"_links":{"self":[{"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/product\/6640"}],"collection":[{"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/comments?post=6640"}],"version-history":[{"count":3,"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/product\/6640\/revisions"}],"predecessor-version":[{"id":82161,"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/product\/6640\/revisions\/82161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/media\/81795"}],"wp:attachment":[{"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/media?parent=6640"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/product_cat?post=6640"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gadgetsguruji.in\/index.php\/wp-json\/wp\/v2\/product_tag?post=6640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}